{"id":148330,"date":"2020-07-08T04:16:50","date_gmt":"2020-07-08T02:16:50","guid":{"rendered":"https:\/\/www.radiopiu.net\/wordpress\/?p=148330"},"modified":"2020-07-08T06:19:23","modified_gmt":"2020-07-08T04:19:23","slug":"varie-opere-del-regime-fascista-che-interessarono-lagordino-di-renato-bona","status":"publish","type":"post","link":"https:\/\/www.radiopiu.net\/wordpress\/varie-opere-del-regime-fascista-che-interessarono-lagordino-di-renato-bona\/","title":{"rendered":"VARIE OPERE DEL REGIME FASCISTA CHE INTERESSARONO L\u2019AGORDINO di RENATO BONA"},"content":{"rendered":"<p><strong>BELLUNO<\/strong> Il 21 aprile 1934 (XII era fascista) la Regia Prefettura di Belluno con la Federazione provinciale fascista diede alle stampe in trecento copie numerate (stabilimento tipografico Panfilo Castaldi di Feltre) il volume \u201cBelluno. Attivit\u00e0 svolta e opere compiute sotto il regime fascista dalle amministrazioni e dagli enti della Provincia\u201d. L\u2019idea fu del vice prefetto Carlo Riva il quale, sull\u2019esempio di quanto era stato fatto in altre province, in occasione della celebrazione del primo decennale del governo fascista, intese raccogliere la documentazione dell\u2019attivit\u00e0 svolta, specialmente nel campo costruttivo e delle opere pubbliche, da tutte le amministrazioni statali e parastatali, da tutti gli enti bellunesi. Nel capitolo riservato all\u2019Amministrazione provinciale, in particolare nel campo delle opere pubbliche e fabbricati per pubblici servizi, largo spazio \u00e8 dedicato all\u2019Agordino: Caserma dei Reali carabinieri di Agordo: nell\u2019anno V acquisto, sistemazione e ampliamento, con spesa di 140.000 lire: \u201cCon l\u2019istituzione della tenenza, risultava insufficiente la vecchia caserma di propriet\u00e0 provinciale, per cui si era deciso di acquistare il fabbricato dei consorti Lise avendo quindi a disposizione 25 locali posti su tre piani, oltre la scuderia e una tettoia\u201d. Casa cantoniera di Caprile con magazzino, rimessa, due alloggi; spesa di L. 40.000 nell\u2019anno VII; la localit\u00e0, si pu\u00f2 leggere, \u00e8 centro importante per la manutenzione stradale della zona e per il ricovero di materiali, di mezzi d\u2019opera e di macchinari. Casa cantoniera di Cencenighe, con magazzino, rimessa e due alloggi: spesa L. 35.000 nell\u2019anno VI; casa cantoniera di Col di foglia a Caprile: ampliamento e adattamento del posto di dogana al vecchio confine politico, con una spesa di 10.000 lire nell\u2019anno X; \u201cl\u2019immobile, ad unico vano, lungo la strada Caprile-Collaz-Cernadoi, in posto isolato e privo di abitazioni, venne trasformato e ingrandito, ricavandovi quattro locali per l\u2019alloggio del cantoniere\u201d. Ancora: Ponticello in muratura e sistemazione stradale a Roncolin, presso Cernadoi (Pieve di Livinallongo) lungo la strada Caprile-Collaz-Cernadoi, con spesa nell\u2019anno X di 22.000 lire; si ricorda che \u201cnella localit\u00e0 esisteva un manufatto in legno, a luce ampia, gi\u00e0 costruito dall\u2019autorit\u00e0 militare durante la guerra (1916) e quindi in condizioni pessime: con economia notevole venne ricostruito in muratura di pietrame, riducendone la luce\u201d. Ponte in legno di rio Scuro presso Collaz (Pieve di Livinallongo), nell\u2019anno IX, con spesa di L. 50.000. Viene precisato che \u201cQuesta ardita opera venne totalmente ricostruita pezzo su pezzo, mantenendo quasi sempre il transito e restringendo la luce rispetto a quella del manufatto vecchio da m. 37 a 24. \u201cAnche questo ponte come quello indicato in precedenza, era stato eseguito dall\u2019autorit\u00e0 militare durante la guerra che, per le esigenze del momento, non pot\u00e9 impiegare legname adatto e stagionato. Le vecchie membrature erano quindi addirittura infracidite e gravi furono le difficolt\u00e0 incontrate per eseguire i lavori a transito aperto, ad esempio le capriate vennero montate in cantiere e poi messe in opera varandole e adattandole all\u2019impalcato sovrastante\u201d. Sistemazione della frana sotto Selva, strada Caprile-Forcella Staulanza-Zoldo, con costruzione di drenaggi, muri di sostegno, canali superficiali di raccolta negli anni IX e X con spesa di L. 20.000. \u201cLe acque sotterranee avevano provocato uno scorrimento di falda, che interessava, in tre punti, la strada per cui era urgente provvedere a togliere il pericolo\u201d. Sistemazione della strada tra Pegazz\u00f9 e Caprile, a valle e monte, con opere di difesa dal torrente Fiorentina, nell\u2019anno X con spesa di L. 25.000. \u201cDa vari anni il torrente Fiorentina continuava a scalzare il piede della scarpata stradale, tanto che durante le morbide primaverili di questo anno era stato interessato fino il piano viabile. A monte della strada si sistem\u00f2 la scarpata con la costruzione di alcune briglie in gabbioni, ed a valle, lungo la sponda del torrente, si provvide alla gettata di grossi blocchi in calcestruzzo di cemento\u201d. Altri interventi: rialzo e sistemazione della strada Agordo-Caprile a S. Maria delle Grazie e difesa in gabbioni sul Cordevole (Alleghe), lunghezza del nuovo tronco m. 1400; nell\u2019anno V, spesa incontrata L. 140.000. Ponte sul torrente Zunaia ad Alleghe, con spalle e pila in muratura, due travate metalliche di m. 13,50 di luce ciascuna, strada Agordo-Caprile, nell\u2019anno VII spesa di lire 35.000. Viene ricordato che \u201cIl vecchio ponte era costituito da 7 luci di oltre 7 metri l\u2019una, con pile e spalle in muratura e travate in legno, e si presentava con notevole obliquit\u00e0 rispetto all\u2019asse della valle. Anche quest\u2019opera era stata eseguita nel 1915-16. Il nuovo manufatto, che presenta una linea semplice ma elegante, venne spostato pi\u00f9 a monte rispetto a quello preesistente e studiato per un carico di 18 tonnellate, ma colla possibilit\u00e0 di essere rapidamente rinforzato fino a raddoppiare la sua portata. Anche i due accessi vennero migliorati\u201d. Allargamento e sistemazioni stradali alla chiusa di Listolade (Taibon) lungo la strada Agordo \u2013Caprile, anno VIII, spesa di L. 15.000. Rettifica stradale a Ronch de Bos (Taibon), lungo la Agordo-Caprile con la costruzione di muri di sostegno e controriva; anno VII, spesa lire 50.000: \u201cLa strada era stretta e planimetricamente ed altimetricamente lasciava a desiderare, tanto che in qualche punto era difficile lo scambio ai veicoli. Venne attuata la rettifica con l\u2019allargamento verso valle, con struttura muraria ad archetti e pilastri\u201d. Infine Rettifica stradale a Toccol, fra Agordo e Le Ville, con la costruzione di un ponticello obliquo, lunghezza m. 700; anno VII, spesa lire 160.000. \u201cLa vecchia strada, attualmente usata ancora dai soli abitanti del luogo, che da Agordo attraversa i villaggi detti Le Ville, specialmente a Parech e Prompicai, si trova nelle condizioni pi\u00f9 infelici per le curve strettissime lungo le quali \u00e8 preclusa ogni visibilit\u00e0 dai fabbricati che la fiancheggiano, con sezioni assolutamente insufficiente al libero incrociarsi dei veicoli, con pendenze e contropendenze accentuate che, specialmente durante l\u2019inverno, per la neve e il ghiaccio, ostacolano sensibilmente ogni genere di traffico. La localit\u00e0 era nota a tutti come la pi\u00f9 pericolosa della zona. Il nuovo tronco venne studiato invece al di fuori dei villaggi, scorre quasi orizzontale, con curve ampie e larghezza di sei metri, ed ha valorizzato fortemente, quali aree fabbricabili, i terreni che lo fiancheggiano\u201d.<\/p>\n\n\t\t\t<style type='text\/css'>\n\t\t\t\t#gallery-1 {\n\t\t\t\t\tmargin: auto;\n\t\t\t\t}\n\t\t\t\t#gallery-1 .gallery-item {\n\t\t\t\t\tfloat: left;\n\t\t\t\t\tmargin-top: 10px;\n\t\t\t\t\ttext-align: center;\n\t\t\t\t\twidth: 33%;\n\t\t\t\t}\n\t\t\t\t#gallery-1 img {\n\t\t\t\t\tborder: 2px solid #cfcfcf;\n\t\t\t\t}\n\t\t\t\t#gallery-1 .gallery-caption {\n\t\t\t\t\tmargin-left: 0;\n\t\t\t\t}\n\t\t\t\t\/* see gallery_shortcode() in wp-includes\/media.php *\/\n\t\t\t<\/style>\n\t\t<div id='gallery-1' class='dt-gallery-container gallery galleryid-148330 gallery-columns-3 gallery-size-thumbnail'><dl class='gallery-item'>\n\t\t\t\t<dt class='gallery-icon landscape'>\n\t\t\t\t\t<a class=\"rollover\" href='https:\/\/www.radiopiu.net\/wordpress\/varie-opere-del-regime-fascista-che-interessarono-lagordino-di-renato-bona\/107356327_904588336709368_2331619063431881467_n\/'><img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/www.radiopiu.net\/wordpress\/wp-content\/uploads\/2020\/07\/107356327_904588336709368_2331619063431881467_n-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" \/><\/a>\n\t\t\t\t<\/dt><\/dl><dl class='gallery-item'>\n\t\t\t\t<dt class='gallery-icon landscape'>\n\t\t\t\t\t<a class=\"rollover\" href='https:\/\/www.radiopiu.net\/wordpress\/varie-opere-del-regime-fascista-che-interessarono-lagordino-di-renato-bona\/107501733_580593586185484_5215525307759951312_n\/'><img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/www.radiopiu.net\/wordpress\/wp-content\/uploads\/2020\/07\/107501733_580593586185484_5215525307759951312_n-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" \/><\/a>\n\t\t\t\t<\/dt><\/dl><dl class='gallery-item'>\n\t\t\t\t<dt class='gallery-icon landscape'>\n\t\t\t\t\t<a class=\"rollover\" href='https:\/\/www.radiopiu.net\/wordpress\/varie-opere-del-regime-fascista-che-interessarono-lagordino-di-renato-bona\/107712354_967388893721437_1971785490334593950_n\/'><img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/www.radiopiu.net\/wordpress\/wp-content\/uploads\/2020\/07\/107712354_967388893721437_1971785490334593950_n-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" \/><\/a>\n\t\t\t\t<\/dt><\/dl><br style=\"clear: both\" \/><dl class='gallery-item'>\n\t\t\t\t<dt class='gallery-icon landscape'>\n\t\t\t\t\t<a class=\"rollover\" href='https:\/\/www.radiopiu.net\/wordpress\/varie-opere-del-regime-fascista-che-interessarono-lagordino-di-renato-bona\/107117634_325447281788676_4402075655832689167_n\/'><img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/www.radiopiu.net\/wordpress\/wp-content\/uploads\/2020\/07\/107117634_325447281788676_4402075655832689167_n-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" \/><\/a>\n\t\t\t\t<\/dt><\/dl><dl class='gallery-item'>\n\t\t\t\t<dt class='gallery-icon landscape'>\n\t\t\t\t\t<a class=\"rollover\" href='https:\/\/www.radiopiu.net\/wordpress\/varie-opere-del-regime-fascista-che-interessarono-lagordino-di-renato-bona\/107102808_3122827721157336_5549236580000242538_n\/'><img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/www.radiopiu.net\/wordpress\/wp-content\/uploads\/2020\/07\/107102808_3122827721157336_5549236580000242538_n-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" \/><\/a>\n\t\t\t\t<\/dt><\/dl>\n\t\t\t\t<br style='clear: both' \/>\n\t\t\t<\/div>\n\n<p>NELLE FOTO (riproduzioni dal libro \u201cLa Provincia di Belluno in regime fascista\u201d): ponticello in muratura a Roncolin sulla Caprile-Collaz-Cernadoi; sistemazioni stradali a Santa Maria delle Grazie; ponte sul torrente Zunaia ad Alleghe; Rettifica stradale a Toccol di Agordo; ponte dei Castei sulla provinciale Belluno-Agordo<\/p>\n","protected":false},"excerpt":{"rendered":"<p>BELLUNO Il 21 aprile 1934 (XII era fascista) la Regia Prefettura di Belluno con la Federazione provinciale fascista diede alle stampe in trecento copie numerate (stabilimento tipografico Panfilo Castaldi di Feltre) il volume \u201cBelluno. Attivit\u00e0 svolta e opere compiute sotto il regime fascista dalle amministrazioni e dagli enti della Provincia\u201d. L\u2019idea fu del vice prefetto&hellip;<\/p>\n","protected":false},"author":1,"featured_media":148335,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":""},"categories":[49],"tags":[],"class_list":["post-148330","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-news-18","category-49","description-off"],"img_url":"https:\/\/www.radiopiu.net\/wordpress\/wp-content\/uploads\/2020\/07\/107117634_325447281788676_4402075655832689167_n.jpg","_links":{"self":[{"href":"https:\/\/www.radiopiu.net\/wordpress\/wp-json\/wp\/v2\/posts\/148330","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.radiopiu.net\/wordpress\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.radiopiu.net\/wordpress\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.radiopiu.net\/wordpress\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.radiopiu.net\/wordpress\/wp-json\/wp\/v2\/comments?post=148330"}],"version-history":[{"count":0,"href":"https:\/\/www.radiopiu.net\/wordpress\/wp-json\/wp\/v2\/posts\/148330\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.radiopiu.net\/wordpress\/wp-json\/wp\/v2\/media\/148335"}],"wp:attachment":[{"href":"https:\/\/www.radiopiu.net\/wordpress\/wp-json\/wp\/v2\/media?parent=148330"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.radiopiu.net\/wordpress\/wp-json\/wp\/v2\/categories?post=148330"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.radiopiu.net\/wordpress\/wp-json\/wp\/v2\/tags?post=148330"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}