{"id":190020,"date":"2021-02-09T15:20:03","date_gmt":"2021-02-09T14:20:03","guid":{"rendered":"https:\/\/www.radiopiu.net\/wordpress\/?p=190020"},"modified":"2021-02-10T06:04:00","modified_gmt":"2021-02-10T05:04:00","slug":"meteo-attese-per-domani-nuove-precipitazioni-stato-di-attenzione-idrogeologica-in-val-zoldana","status":"publish","type":"post","link":"https:\/\/www.radiopiu.net\/wordpress\/meteo-attese-per-domani-nuove-precipitazioni-stato-di-attenzione-idrogeologica-in-val-zoldana\/","title":{"rendered":"METEO. ATTESE PER DOMANI NUOVE PRECIPITAZIONI. STATO DI ATTENZIONE IDROGEOLOGICA IN VAL ZOLDANA"},"content":{"rendered":"<p><strong>VENEZIA <\/strong>Le previsioni meteo indicazioni per domani mercoled\u00ec 10 tempo perturbato specie in mattinata, quando sono previste precipitazioni estese, pi\u00f9 consistenti sulle zone centro settentrionali del Veneto. Limite delle nevicate intorno a 900-1200 m. Saranno probabili anche dei rovesci e qualche occasionale temporale in pianura. Nel pomeriggio tendenza ad attenuazione dei fenomeni e successiva cessazione. Alla luce delle previsioni meteo, il Centro Funzionale Decentrato della Regione del Veneto ha emesso un avviso di criticit\u00e0 idrogeologica gialla sulla zona dell\u2019alto Piave Bellunese. Si tratta di una criticit\u00e0 legata sia alle pregresse condizioni di saturazione dei suoli, che possono amplificare gli effetti al suolo delle precipitazioni, sia alla riattivazione di fenomeni di dissesto idrogeologico di dimensioni significative, in particolare in val Zoldana e presso la frana della Busa del Cristo a Perarolo (BL).<\/p>\n<p><a href=\"https:\/\/www.radiopiu.net\/wordpress\/meteo-attese-per-domani-nuove-precipitazioni-stato-di-attenzione-idrogeologica-in-val-zoldana\/schermata-2021-02-09-alle-15-18-44\/\" rel=\"attachment wp-att-190021\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-190021 size-large\" src=\"https:\/\/www.radiopiu.net\/wordpress\/wp-content\/uploads\/2021\/02\/Schermata-2021-02-09-alle-15.18.44-1024x346.png\" alt=\"\" width=\"1024\" height=\"346\" srcset=\"https:\/\/www.radiopiu.net\/wordpress\/wp-content\/uploads\/2021\/02\/Schermata-2021-02-09-alle-15.18.44-1024x346.png 1024w, https:\/\/www.radiopiu.net\/wordpress\/wp-content\/uploads\/2021\/02\/Schermata-2021-02-09-alle-15.18.44-300x101.png 300w, https:\/\/www.radiopiu.net\/wordpress\/wp-content\/uploads\/2021\/02\/Schermata-2021-02-09-alle-15.18.44-768x260.png 768w, https:\/\/www.radiopiu.net\/wordpress\/wp-content\/uploads\/2021\/02\/Schermata-2021-02-09-alle-15.18.44.png 1290w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>VENEZIA Le previsioni meteo indicazioni per domani mercoled\u00ec 10 tempo perturbato specie in mattinata, quando sono previste precipitazioni estese, pi\u00f9 consistenti sulle zone centro settentrionali del Veneto. Limite delle nevicate intorno a 900-1200 m. Saranno probabili anche dei rovesci e qualche occasionale temporale in pianura. Nel pomeriggio tendenza ad attenuazione dei fenomeni e successiva cessazione.&hellip;<\/p>\n","protected":false},"author":4,"featured_media":144264,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":""},"categories":[51,49],"tags":[],"class_list":["post-190020","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-evidenza-top","category-news-18","category-51","category-49","description-off"],"img_url":"https:\/\/www.radiopiu.net\/wordpress\/wp-content\/uploads\/2020\/06\/PIOGGIA.jpg","_links":{"self":[{"href":"https:\/\/www.radiopiu.net\/wordpress\/wp-json\/wp\/v2\/posts\/190020","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.radiopiu.net\/wordpress\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.radiopiu.net\/wordpress\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.radiopiu.net\/wordpress\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.radiopiu.net\/wordpress\/wp-json\/wp\/v2\/comments?post=190020"}],"version-history":[{"count":0,"href":"https:\/\/www.radiopiu.net\/wordpress\/wp-json\/wp\/v2\/posts\/190020\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.radiopiu.net\/wordpress\/wp-json\/wp\/v2\/media\/144264"}],"wp:attachment":[{"href":"https:\/\/www.radiopiu.net\/wordpress\/wp-json\/wp\/v2\/media?parent=190020"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.radiopiu.net\/wordpress\/wp-json\/wp\/v2\/categories?post=190020"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.radiopiu.net\/wordpress\/wp-json\/wp\/v2\/tags?post=190020"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}