{"id":220043,"date":"2021-07-05T15:10:37","date_gmt":"2021-07-05T13:10:37","guid":{"rendered":"https:\/\/www.radiopiu.net\/wordpress\/?p=220043"},"modified":"2021-07-05T15:10:37","modified_gmt":"2021-07-05T13:10:37","slug":"scivola-per-decine-di-metri-si-ferma-sopra-il-salto-di-roccia","status":"publish","type":"post","link":"https:\/\/www.radiopiu.net\/wordpress\/scivola-per-decine-di-metri-si-ferma-sopra-il-salto-di-roccia\/","title":{"rendered":"SCIVOLA PER DECINE DI METRI, SI FERMA SOPRA IL SALTO DI ROCCIA"},"content":{"rendered":"<blockquote><p><strong><img loading=\"lazy\" decoding=\"async\" class=\"alignleft\" src=\"https:\/\/www.radiopiu.net\/wordpress\/wp-content\/uploads\/2020\/11\/salt_20201115_210146_846.jpg\" width=\"162\" height=\"122\" \/>ALPAGO\u00a0<\/strong> L&#8217;elicottero di Treviso emergenza alle 13 \u00e8 decollato in direzione dell&#8217;Alpago, per un&#8217;escursionista ruzzolata per una trentina di metri lungo un ghiaione. R.T., 57 anni, di Vittorio Veneto (TV), stava percorrendo il sentiero numero 926 che porta al Rifugio Semenza quando, perso l&#8217;equilibrio, \u00e8 caduta di lato fermandosi dopo alcune decine di metri sopra un salto di roccia. Il compagno \u00e8 quindi corso a cercare copertura telefonica per lanciare l&#8217;allarme. Individuato il punto in cui si trovava la donna, l&#8217;eliambulanza ha sbarcato con un verricello di 15 metri tecnico di elisoccorso e medico. Stabilizzata per un possibile trauma alla gamba, l&#8217;infortunata \u00e8 stata issata a bordo, per essere trasportata all&#8217;ospedale di Conegliano.<\/p><\/blockquote>\n","protected":false},"excerpt":{"rendered":"<p>ALPAGO\u00a0 L&#8217;elicottero di Treviso emergenza alle 13 \u00e8 decollato in direzione dell&#8217;Alpago, per un&#8217;escursionista ruzzolata per una trentina di metri lungo un ghiaione. R.T., 57 anni, di Vittorio Veneto (TV), stava percorrendo il sentiero numero 926 che porta al Rifugio Semenza quando, perso l&#8217;equilibrio, \u00e8 caduta di lato fermandosi dopo alcune decine di metri sopra&hellip;<\/p>\n","protected":false},"author":4,"featured_media":173023,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":""},"categories":[51,49],"tags":[],"class_list":["post-220043","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-evidenza-top","category-news-18","category-51","category-49","description-off"],"img_url":"https:\/\/www.radiopiu.net\/wordpress\/wp-content\/uploads\/2020\/11\/salt_20201115_210146_846.jpg","_links":{"self":[{"href":"https:\/\/www.radiopiu.net\/wordpress\/wp-json\/wp\/v2\/posts\/220043","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.radiopiu.net\/wordpress\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.radiopiu.net\/wordpress\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.radiopiu.net\/wordpress\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.radiopiu.net\/wordpress\/wp-json\/wp\/v2\/comments?post=220043"}],"version-history":[{"count":0,"href":"https:\/\/www.radiopiu.net\/wordpress\/wp-json\/wp\/v2\/posts\/220043\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.radiopiu.net\/wordpress\/wp-json\/wp\/v2\/media\/173023"}],"wp:attachment":[{"href":"https:\/\/www.radiopiu.net\/wordpress\/wp-json\/wp\/v2\/media?parent=220043"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.radiopiu.net\/wordpress\/wp-json\/wp\/v2\/categories?post=220043"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.radiopiu.net\/wordpress\/wp-json\/wp\/v2\/tags?post=220043"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}