{"id":293502,"date":"2022-08-19T05:32:41","date_gmt":"2022-08-19T03:32:41","guid":{"rendered":"https:\/\/www.radiopiu.net\/wordpress\/?p=293502"},"modified":"2022-08-19T08:51:01","modified_gmt":"2022-08-19T06:51:01","slug":"criptovalute-persi-100mila-euro-di-investimenti","status":"publish","type":"post","link":"https:\/\/www.radiopiu.net\/wordpress\/criptovalute-persi-100mila-euro-di-investimenti\/","title":{"rendered":"CRIPTOVALUTE, PERSI 100MILA EURO DI INVESTIMENTI"},"content":{"rendered":"<p><strong>BELLUNO Oggi sul Corriere delle Alpi, di Cristina Contento<\/strong><\/p>\n<p><strong><img loading=\"lazy\" decoding=\"async\" class=\"alignleft\" src=\"https:\/\/www.radiopiu.net\/wordpress\/wp-content\/uploads\/2021\/07\/9dab3da2-5b99-4e4c-9808-d95d42ff43b5-300x300.jpg\" width=\"161\" height=\"161\" \/>BELLUNO Oggi sul Corriere delle Alpi, di Cristina Contento<\/strong><\/p>\n<p>Ci sono i primi tre o quattro investitori bellunesi vittime nel bailamme esploso con l&#8217;inchiesta sulla New Financial Technology, la societ\u00e0 trevigiana che operava nel mercato delle criptovalute e dei bitcoin nel mirino della Finanza. Nft con loro avrebbe rastrellato poco meno di centomila euro, inclusi gli investimenti di un cliente emiliano che si \u00e8 rivolto a un avvocato bellunese, Valentina Stefani, per cercare di recuperare almeno il capitale investito. L&#8217;inchiesta proprio in questi giorni ha avuto una accelerata con l&#8217;iscrizione nel registro degli indagati di sei persone. Almeno 300 milioni di euro si ipotizzano raccolti da circa 6000 investitori.Fra questi c&#8217;\u00e8 chi ha versato i risparmi di un lavoro subordinato, da dipendente&#8230;.<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<hr \/>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>BELLUNO Oggi sul Corriere delle Alpi, di Cristina Contento BELLUNO Oggi sul Corriere delle Alpi, di Cristina Contento Ci sono i primi tre o quattro investitori bellunesi vittime nel bailamme esploso con l&#8217;inchiesta sulla New Financial Technology, la societ\u00e0 trevigiana che operava nel mercato delle criptovalute e dei bitcoin nel mirino della Finanza. Nft con&hellip;<\/p>\n","protected":false},"author":4,"featured_media":222502,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":""},"categories":[51,49],"tags":[],"class_list":["post-293502","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-evidenza-top","category-news-18","category-51","category-49","description-off"],"img_url":"https:\/\/www.radiopiu.net\/wordpress\/wp-content\/uploads\/2021\/07\/9dab3da2-5b99-4e4c-9808-d95d42ff43b5.jpg","_links":{"self":[{"href":"https:\/\/www.radiopiu.net\/wordpress\/wp-json\/wp\/v2\/posts\/293502","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.radiopiu.net\/wordpress\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.radiopiu.net\/wordpress\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.radiopiu.net\/wordpress\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.radiopiu.net\/wordpress\/wp-json\/wp\/v2\/comments?post=293502"}],"version-history":[{"count":0,"href":"https:\/\/www.radiopiu.net\/wordpress\/wp-json\/wp\/v2\/posts\/293502\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.radiopiu.net\/wordpress\/wp-json\/wp\/v2\/media\/222502"}],"wp:attachment":[{"href":"https:\/\/www.radiopiu.net\/wordpress\/wp-json\/wp\/v2\/media?parent=293502"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.radiopiu.net\/wordpress\/wp-json\/wp\/v2\/categories?post=293502"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.radiopiu.net\/wordpress\/wp-json\/wp\/v2\/tags?post=293502"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}