{"id":360743,"date":"2023-11-09T05:54:17","date_gmt":"2023-11-09T04:54:17","guid":{"rendered":"https:\/\/www.radiopiu.net\/wordpress\/?p=360743"},"modified":"2023-11-10T06:05:31","modified_gmt":"2023-11-10T05:05:31","slug":"cencenighe-la-valle-abbonati-allinquinamento-delle-acque-e-ai-mancati-ristori","status":"publish","type":"post","link":"https:\/\/www.radiopiu.net\/wordpress\/cencenighe-la-valle-abbonati-allinquinamento-delle-acque-e-ai-mancati-ristori\/","title":{"rendered":"CENCENIGHE, LA VALLE: ABBONATI ALL&#8217;INQUINAMENTO DELLE ACQUE"},"content":{"rendered":"<p><strong><img decoding=\"async\" class=\"alignleft\" src=\"https:\/\/www.radiopiu.net\/wordpress\/wp-content\/uploads\/2021\/06\/th-12.jpg\" \/>CENCENIGHE<\/strong> Ed ora quanti giorni trascorreranno prima della cessata emergenza? Una settimana come nei casi miglior, o 10-15 giorni come pi\u00f9 volte riscontrato. Famiglie costrette a centellinare l&#8217;acqua e comperarla per sicurezza al supermercato, oppure prendere la tanica per mettersi in fila all&#8217;autobotte. In attesa che dagli uffici di Belluno di GSP venga dato l&#8217;ordine di inviare la bolletta per un servizio idrico che lascia a desiderare. A Cencenighe di sicuro:\u00a0 acqua in quinata in localit\u00e0 PRA&#8217; DI MEZZO e\u00a0 non pu\u00f2 essere usata per scopi alimentari. Verr\u00e0 effettuato servizio sostitutivo con cisterna in localit\u00e0 Pr\u00e0 di Mezzo.<\/p>\n<p><strong>LA VALLE\u00a0<\/strong> Acqua inquinata a RONCHE, NOACH, LE CAMPE e CANCELLADE\u00a0 non \u00e8 potabile e non pu\u00f2 essere usata per scopi alimentari. Verr\u00e0 effettuato servizio sostitutivo con autobotte in localit\u00e0 Le Campe e con cisterna in localit\u00e0 Ronche.<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<hr \/>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>CENCENIGHE Ed ora quanti giorni trascorreranno prima della cessata emergenza? Una settimana come nei casi miglior, o 10-15 giorni come pi\u00f9 volte riscontrato. Famiglie costrette a centellinare l&#8217;acqua e comperarla per sicurezza al supermercato, oppure prendere la tanica per mettersi in fila all&#8217;autobotte. In attesa che dagli uffici di Belluno di GSP venga dato l&#8217;ordine&hellip;<\/p>\n","protected":false},"author":4,"featured_media":216172,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":""},"categories":[104],"tags":[],"class_list":["post-360743","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-evidenza_3","category-104","description-off"],"img_url":"https:\/\/www.radiopiu.net\/wordpress\/wp-content\/uploads\/2021\/06\/th-12.jpg","_links":{"self":[{"href":"https:\/\/www.radiopiu.net\/wordpress\/wp-json\/wp\/v2\/posts\/360743","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.radiopiu.net\/wordpress\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.radiopiu.net\/wordpress\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.radiopiu.net\/wordpress\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.radiopiu.net\/wordpress\/wp-json\/wp\/v2\/comments?post=360743"}],"version-history":[{"count":0,"href":"https:\/\/www.radiopiu.net\/wordpress\/wp-json\/wp\/v2\/posts\/360743\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.radiopiu.net\/wordpress\/wp-json\/wp\/v2\/media\/216172"}],"wp:attachment":[{"href":"https:\/\/www.radiopiu.net\/wordpress\/wp-json\/wp\/v2\/media?parent=360743"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.radiopiu.net\/wordpress\/wp-json\/wp\/v2\/categories?post=360743"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.radiopiu.net\/wordpress\/wp-json\/wp\/v2\/tags?post=360743"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}