{"id":480444,"date":"2025-11-13T22:42:16","date_gmt":"2025-11-13T21:42:16","guid":{"rendered":"https:\/\/www.radiopiu.net\/wordpress\/?p=480444"},"modified":"2025-11-14T05:39:22","modified_gmt":"2025-11-14T04:39:22","slug":"seconda-sconfitta-consecutiva-per-le-civette-lappiano-espugna-il-de-toni-il-feltre-torna-a-vincere","status":"publish","type":"post","link":"https:\/\/www.radiopiu.net\/wordpress\/seconda-sconfitta-consecutiva-per-le-civette-lappiano-espugna-il-de-toni-il-feltre-torna-a-vincere\/","title":{"rendered":"SECONDA SCONFITTA CONSECUTIVA PER LE CIVETTE. L&#8217;APPIANO ESPUGNA IL DE TONI. IL FELTRE TORNA A VINCERE"},"content":{"rendered":"<p>********<\/p>\n<p>&nbsp;<\/p>\n<p><strong>DI MARCO GAZ<\/strong><\/p>\n<p><span style=\"color: #ff0000;\"><strong>IHL \u2013 RECUPERO 10\u00b0 GIORNATA<\/strong><\/span><\/p>\n<p><strong>ALLEGHE \u2013 APPIANO 3-4<\/strong><\/p>\n<p>PARZIALI: 2-0, 0-3, 1-1<\/p>\n<p>GOL: pt. 10\u201938\u201d Alessio, 12\u201917\u201d D. Iori. st. 1\u201911\u201d e 9\u201945\u201d Eruzione, 15\u201915\u201d Amici. tt. 2\u201940\u201d Radin, 6\u201903\u201d Isiguzo<\/p>\n<p>Una sconfitta che brucia per l\u2019Alleghe che perde in casa contro l\u2019Appiano. Di fronte agli oltre 450 spettatori del De Toni, gli agordini giocano bene la prima e la terza frazione. Fatali i 20\u2019 centrali dove gli altoatesini fanno la voce grossa ribaltando il risultato dopo che i biancorossi erano passati in doppio vantaggio. Terzo tempo con i padroni di casa che le provano tutte, accorciano le distanze ma non riescono a pareggiare la sfida. Sabato di nuovo in campo con gli alleghesi in trasferta contro il Valpellice. \u00a0La prima parte di partita scorre veloce. Le civette passano indenni la prima penalit\u00e0 a sfavore. Pochi i tiri in porta da parte delle due formazioni. Il gioco \u00e8 vivace ma le squadre stentano a concludere verso la porta. Il match si sblocca a met\u00e0 primo tempo. A spingere il disco in fondo alla porta ci pensa Alessio che sfrutta un assist d\u2019oro di Isiguzo. L\u2019Appiano prova la reazione ma la difesa agordina \u00e8 attenta. Ma al primo contropiede De Toni scappa e serve al centro per Diego Iori che non sbaglia. I pirati iniziano la seconda frazione ingranando la marcia giusta e dopo appena un minuto riapre il match con la rete di Eruzione. il gioco \u00e8 maschio e gli arbitri sono costretti ad infliggere qualche penalit\u00e0. Ad avere la meglio sono gli altoatesini che sfruttano un powerplay pareggiando i conti ancora con Eruzione. L\u2019Appiano sembra avere in mano la partita prendendo di mira la porta difesa da De Nardin. Biancorossi che provano la reazione e si avvicinano al gol con De Toni. Ma i pirati colpiscono in contropiede: ci pensa Amici a portare in vantaggio la squadra ospite. L\u2019Alleghe sembra un\u2019altra squadra al rientro dall\u2019ultima pausa. Le occasioni non mancano ma anche le penalit\u00e0 nei confronti dei padroni di casa. L\u2019Appiano gestisce il vantaggio e si fa pericoloso con Eruzione. A calare il poker altoatesino ci pensa Radin in superiorit\u00e0 numerica con un missile dalla linea blu. A riaccendere le speranze per le civette ci pensa Isiguzo che batte il portiere avversario. Le provano tutte gli agordini ma il pareggio non arriva. Un vero e e proprio assedio degli alleghesi che non concedono spazi ai pirati che non devono far altro che difendere il gol di vantaggio. Ultimi minuti con i padroni di casa che giocano la carta dell\u2019uomo di movimento in pi\u00f9, ma il gol non arriva.<\/p>\n<p><strong>LE FOTO DI MATTEO FLORIDIA<\/strong><\/p>\n\n\t\t\t<style type='text\/css'>\n\t\t\t\t#gallery-1 {\n\t\t\t\t\tmargin: auto;\n\t\t\t\t}\n\t\t\t\t#gallery-1 .gallery-item {\n\t\t\t\t\tfloat: left;\n\t\t\t\t\tmargin-top: 10px;\n\t\t\t\t\ttext-align: center;\n\t\t\t\t\twidth: 25%;\n\t\t\t\t}\n\t\t\t\t#gallery-1 img {\n\t\t\t\t\tborder: 2px solid #cfcfcf;\n\t\t\t\t}\n\t\t\t\t#gallery-1 .gallery-caption {\n\t\t\t\t\tmargin-left: 0;\n\t\t\t\t}\n\t\t\t\t\/* see gallery_shortcode() in wp-includes\/media.php *\/\n\t\t\t<\/style>\n\t\t<div id='gallery-1' class='dt-gallery-container gallery galleryid-480444 gallery-columns-4 gallery-size-thumbnail'><dl class='gallery-item'>\n\t\t\t\t<dt class='gallery-icon landscape'>\n\t\t\t\t\t<a class=\"rollover rollover-zoom dt-pswp-item\" title=\"f17e5c45-45d1-4706-9787-781ece2b3ac7\" data-dt-img-description=\"\" data-large_image_width=\"1600\" data-large_image_height=\"1211\"href='https:\/\/www.radiopiu.net\/wordpress\/wp-content\/uploads\/2025\/11\/f17e5c45-45d1-4706-9787-781ece2b3ac7.jpg'><img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/www.radiopiu.net\/wordpress\/wp-content\/uploads\/2025\/11\/f17e5c45-45d1-4706-9787-781ece2b3ac7-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" \/><\/a>\n\t\t\t\t<\/dt><\/dl><dl class='gallery-item'>\n\t\t\t\t<dt class='gallery-icon landscape'>\n\t\t\t\t\t<a class=\"rollover rollover-zoom dt-pswp-item\" title=\"b695e082-7aa7-462e-ac8d-e4698bdf9663\" data-dt-img-description=\"\" data-large_image_width=\"1600\" data-large_image_height=\"1228\"href='https:\/\/www.radiopiu.net\/wordpress\/wp-content\/uploads\/2025\/11\/b695e082-7aa7-462e-ac8d-e4698bdf9663.jpg'><img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/www.radiopiu.net\/wordpress\/wp-content\/uploads\/2025\/11\/b695e082-7aa7-462e-ac8d-e4698bdf9663-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" \/><\/a>\n\t\t\t\t<\/dt><\/dl><dl class='gallery-item'>\n\t\t\t\t<dt class='gallery-icon landscape'>\n\t\t\t\t\t<a class=\"rollover rollover-zoom dt-pswp-item\" title=\"4c2fd8fc-e4b2-496a-aae7-7bcb340fbcf0\" data-dt-img-description=\"\" data-large_image_width=\"1600\" data-large_image_height=\"1186\"href='https:\/\/www.radiopiu.net\/wordpress\/wp-content\/uploads\/2025\/11\/4c2fd8fc-e4b2-496a-aae7-7bcb340fbcf0.jpg'><img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/www.radiopiu.net\/wordpress\/wp-content\/uploads\/2025\/11\/4c2fd8fc-e4b2-496a-aae7-7bcb340fbcf0-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" \/><\/a>\n\t\t\t\t<\/dt><\/dl><dl class='gallery-item'>\n\t\t\t\t<dt class='gallery-icon landscape'>\n\t\t\t\t\t<a class=\"rollover rollover-zoom dt-pswp-item\" title=\"0c4cf809-03bc-406a-bdc3-1a0d6bfffdc9\" data-dt-img-description=\"\" data-large_image_width=\"1600\" data-large_image_height=\"1216\"href='https:\/\/www.radiopiu.net\/wordpress\/wp-content\/uploads\/2025\/11\/0c4cf809-03bc-406a-bdc3-1a0d6bfffdc9.jpg'><img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/www.radiopiu.net\/wordpress\/wp-content\/uploads\/2025\/11\/0c4cf809-03bc-406a-bdc3-1a0d6bfffdc9-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" \/><\/a>\n\t\t\t\t<\/dt><\/dl><br style=\"clear: both\" \/><dl class='gallery-item'>\n\t\t\t\t<dt class='gallery-icon landscape'>\n\t\t\t\t\t<a class=\"rollover rollover-zoom dt-pswp-item\" title=\"bf88584c-5af3-4db1-a2c5-c9763c7c771f\" data-dt-img-description=\"\" data-large_image_width=\"1600\" data-large_image_height=\"988\"href='https:\/\/www.radiopiu.net\/wordpress\/wp-content\/uploads\/2025\/11\/bf88584c-5af3-4db1-a2c5-c9763c7c771f.jpg'><img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/www.radiopiu.net\/wordpress\/wp-content\/uploads\/2025\/11\/bf88584c-5af3-4db1-a2c5-c9763c7c771f-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" \/><\/a>\n\t\t\t\t<\/dt><\/dl><dl class='gallery-item'>\n\t\t\t\t<dt class='gallery-icon landscape'>\n\t\t\t\t\t<a class=\"rollover rollover-zoom dt-pswp-item\" title=\"40703b4f-8f45-49b6-b90c-133734bcb8a0\" data-dt-img-description=\"\" data-large_image_width=\"1600\" data-large_image_height=\"1329\"href='https:\/\/www.radiopiu.net\/wordpress\/wp-content\/uploads\/2025\/11\/40703b4f-8f45-49b6-b90c-133734bcb8a0.jpg'><img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/www.radiopiu.net\/wordpress\/wp-content\/uploads\/2025\/11\/40703b4f-8f45-49b6-b90c-133734bcb8a0-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" \/><\/a>\n\t\t\t\t<\/dt><\/dl><dl class='gallery-item'>\n\t\t\t\t<dt class='gallery-icon landscape'>\n\t\t\t\t\t<a class=\"rollover rollover-zoom dt-pswp-item\" title=\"9eac9592-9e0b-4856-a280-b4403e452938\" data-dt-img-description=\"\" data-large_image_width=\"1600\" data-large_image_height=\"1034\"href='https:\/\/www.radiopiu.net\/wordpress\/wp-content\/uploads\/2025\/11\/9eac9592-9e0b-4856-a280-b4403e452938.jpg'><img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/www.radiopiu.net\/wordpress\/wp-content\/uploads\/2025\/11\/9eac9592-9e0b-4856-a280-b4403e452938-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" \/><\/a>\n\t\t\t\t<\/dt><\/dl><dl class='gallery-item'>\n\t\t\t\t<dt class='gallery-icon landscape'>\n\t\t\t\t\t<a class=\"rollover rollover-zoom dt-pswp-item\" title=\"fa218546-aa58-4530-acdb-89eb34b00f85\" data-dt-img-description=\"\" data-large_image_width=\"1600\" data-large_image_height=\"1017\"href='https:\/\/www.radiopiu.net\/wordpress\/wp-content\/uploads\/2025\/11\/fa218546-aa58-4530-acdb-89eb34b00f85.jpg'><img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/www.radiopiu.net\/wordpress\/wp-content\/uploads\/2025\/11\/fa218546-aa58-4530-acdb-89eb34b00f85-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" \/><\/a>\n\t\t\t\t<\/dt><\/dl><br style=\"clear: both\" \/>\n\t\t\t<\/div>\n\n<p>&nbsp;<\/p>\n<p><strong>FIEMME \u2013 FELTRE 2-4<\/strong><\/p>\n<p>PARZIALI: 1-1, 0-1, 1-2<\/p>\n<p>GOL: pt. 10\u201941\u201d Moberg, 19\u201929\u201d M. Dall\u2019Agnol. st. 15\u201936\u201d Simionato. tt. 7\u201948\u201d Cortese, 16\u201957\u201d M. Dall\u2019Agnol, 19\u201946\u201d Odorizzi<\/p>\n<p>Dopo cinque turni a secco di punti, il Feltre torna a vincere e lo fa in trasferta contro il Fiemme. Buona prestazione dei feltrini che, dopo una prima frazione da dimenticare, ingranano la marcia giusta nel secondo tempo chiudendo la sfida nel terzo parziale. Sabato picchi ancora in trasferta per giocare contro il Pergine.\u00a0 Padroni di casa che iniziano con il piede giusto la sfida. Il Feltre stenta a farsi vivo davanti alla porta trentina. Dopo una serie di tentativi andati a vuoto il Fiemme sblocca il punteggio. I picchi reagiscono a fine primo tempo pareggiando i conti con Dall\u2019Agnol. Nella seconda frazione il Fiemme tiene in mano la sfida e si avvicina di nuovo al gol. Feltrini che si svegliano nella seconda parte del drittel centrale. I picchi si portano in vantaggio con Simionato. Nel terzo tempo il Feltre chiude la partita calando il poker con le reti di Cortese e dall\u2019Agnol. Nel finale il Fiemme trova il secondo gol della serata.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>******** &nbsp; DI MARCO GAZ IHL \u2013 RECUPERO 10\u00b0 GIORNATA ALLEGHE \u2013 APPIANO 3-4 PARZIALI: 2-0, 0-3, 1-1 GOL: pt. 10\u201938\u201d Alessio, 12\u201917\u201d D. Iori. st. 1\u201911\u201d e 9\u201945\u201d Eruzione, 15\u201915\u201d Amici. tt. 2\u201940\u201d Radin, 6\u201903\u201d Isiguzo Una sconfitta che brucia per l\u2019Alleghe che perde in casa contro l\u2019Appiano. Di fronte agli oltre 450 spettatori&hellip;<\/p>\n","protected":false},"author":4,"featured_media":480452,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":""},"categories":[51,49],"tags":[],"class_list":["post-480444","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-evidenza-top","category-news-18","category-51","category-49","description-off"],"img_url":"https:\/\/www.radiopiu.net\/wordpress\/wp-content\/uploads\/2025\/11\/fa218546-aa58-4530-acdb-89eb34b00f85.jpg","_links":{"self":[{"href":"https:\/\/www.radiopiu.net\/wordpress\/wp-json\/wp\/v2\/posts\/480444","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.radiopiu.net\/wordpress\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.radiopiu.net\/wordpress\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.radiopiu.net\/wordpress\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.radiopiu.net\/wordpress\/wp-json\/wp\/v2\/comments?post=480444"}],"version-history":[{"count":0,"href":"https:\/\/www.radiopiu.net\/wordpress\/wp-json\/wp\/v2\/posts\/480444\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.radiopiu.net\/wordpress\/wp-json\/wp\/v2\/media\/480452"}],"wp:attachment":[{"href":"https:\/\/www.radiopiu.net\/wordpress\/wp-json\/wp\/v2\/media?parent=480444"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.radiopiu.net\/wordpress\/wp-json\/wp\/v2\/categories?post=480444"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.radiopiu.net\/wordpress\/wp-json\/wp\/v2\/tags?post=480444"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}