{"id":496188,"date":"2026-02-11T17:17:10","date_gmt":"2026-02-11T16:17:10","guid":{"rendered":"https:\/\/www.radiopiu.net\/wordpress\/?p=496188"},"modified":"2026-02-11T17:17:10","modified_gmt":"2026-02-11T16:17:10","slug":"sedico-accoglie-la-pianta-della-legalita-dedicata-a-giovanni-falcone","status":"publish","type":"post","link":"https:\/\/www.radiopiu.net\/wordpress\/sedico-accoglie-la-pianta-della-legalita-dedicata-a-giovanni-falcone\/","title":{"rendered":"SEDICO ACCOGLIE LA PIANTA DELLA LEGALIT\u00c0 DEDICATA A GIOVANNI FALCONE"},"content":{"rendered":"<p>*********<\/p>\n<p>&nbsp;<\/p>\n<p><strong><a class=\"dt-pswp-item\" href=\"https:\/\/www.radiopiu.net\/wordpress\/wp-content\/uploads\/2026\/02\/44ce1649-5131-45dd-bfd9-72bd5217a325.jpg\" data-dt-img-description=\"\" data-large_image_width=\"1219\" data-large_image_height=\"871\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter  wp-image-496187\" src=\"https:\/\/www.radiopiu.net\/wordpress\/wp-content\/uploads\/2026\/02\/44ce1649-5131-45dd-bfd9-72bd5217a325-300x214.jpg\" alt=\"\" width=\"219\" height=\"156\" srcset=\"https:\/\/www.radiopiu.net\/wordpress\/wp-content\/uploads\/2026\/02\/44ce1649-5131-45dd-bfd9-72bd5217a325-300x214.jpg 300w, https:\/\/www.radiopiu.net\/wordpress\/wp-content\/uploads\/2026\/02\/44ce1649-5131-45dd-bfd9-72bd5217a325-1024x732.jpg 1024w, https:\/\/www.radiopiu.net\/wordpress\/wp-content\/uploads\/2026\/02\/44ce1649-5131-45dd-bfd9-72bd5217a325-768x549.jpg 768w, https:\/\/www.radiopiu.net\/wordpress\/wp-content\/uploads\/2026\/02\/44ce1649-5131-45dd-bfd9-72bd5217a325.jpg 1219w\" sizes=\"auto, (max-width: 219px) 100vw, 219px\" \/><\/a>\u00a0<\/strong><\/p>\n<p><strong>SEDICO <\/strong>Si \u00e8 tenuta\u00a0questa mattina, presso il Municipio di Sedico, la cerimonia di consegna della\u00a0\u201cPianta della Legalit\u00e0\u201d, un esemplare duplicato dal celebre\u00a0Ficus macrophilla che cresce davanti alla dimora del giudice Giovanni Falcone a Palermo. L\u2019iniziativa, promossa dal raggruppamento Carabinieri Biodiversit\u00e0, rientra nel progetto nazionale \u201cUn albero per il futuro\u201d, volto a creare un grande bosco diffuso della legalit\u00e0 in tutta Italia. Alla cerimonia hanno partecipato il Sindaco di Sedico, i rappresentanti dei Carabinieri Forestali, l\u2019Assessore Daniela Piccoli e la Consigliera delegata alla Cultura Francesca Meneguolo. &#8220;Ricevere questo albero non \u00e8 solo un atto simbolico, ma un impegno concreto che la nostra comunit\u00e0 assume nei confronti delle giovani generazioni,&#8221; ha dichiarato il\u00a0Sindaco di Sedico. &#8220;La pianta di Falcone porta con s\u00e9 la memoria di chi ha sacrificato la vita per la giustizia. Vederla crescere qui, nel cuore di Sedico, ricorder\u00e0 a tutti noi che la legalit\u00e0 va coltivata quotidianamente, con piccoli gesti di responsabilit\u00e0 e rispetto per il bene comune.&#8221; La pianta consegnata dal Tenente Collonello Elisabetta Tropea, dei Carabinieri Forestali \u00e8 stata generata per talea dal Centro Nazionale per la Biodiversit\u00e0 Forestale di Pieve Santo Stefano. Grazie alla geolocalizzazione, ogni albero entra a far parte di una rete nazionale monitorabile online, che testimonia l&#8217;impegno dell&#8217;Italia nel contrasto alle mafie e nella tutela dell&#8217;ambiente. L&#8217;Albero di Falcone diventer\u00e0 ora un punto di riferimento educativo per la cittadinanza, un &#8220;monumento vivo&#8221; che crescer\u00e0 insieme alla Comunit\u00e0 di Sedico.<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>*********<\/p>\n","protected":false},"excerpt":{"rendered":"<p>********* &nbsp; \u00a0 SEDICO Si \u00e8 tenuta\u00a0questa mattina, presso il Municipio di Sedico, la cerimonia di consegna della\u00a0\u201cPianta della Legalit\u00e0\u201d, un esemplare duplicato dal celebre\u00a0Ficus macrophilla che cresce davanti alla dimora del giudice Giovanni Falcone a Palermo. L\u2019iniziativa, promossa dal raggruppamento Carabinieri Biodiversit\u00e0, rientra nel progetto nazionale \u201cUn albero per il futuro\u201d, volto a creare&hellip;<\/p>\n","protected":false},"author":4,"featured_media":496187,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":""},"categories":[104,49],"tags":[],"class_list":["post-496188","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-evidenza_3","category-news-18","category-104","category-49","description-off"],"img_url":"https:\/\/www.radiopiu.net\/wordpress\/wp-content\/uploads\/2026\/02\/44ce1649-5131-45dd-bfd9-72bd5217a325.jpg","_links":{"self":[{"href":"https:\/\/www.radiopiu.net\/wordpress\/wp-json\/wp\/v2\/posts\/496188","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.radiopiu.net\/wordpress\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.radiopiu.net\/wordpress\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.radiopiu.net\/wordpress\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.radiopiu.net\/wordpress\/wp-json\/wp\/v2\/comments?post=496188"}],"version-history":[{"count":0,"href":"https:\/\/www.radiopiu.net\/wordpress\/wp-json\/wp\/v2\/posts\/496188\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.radiopiu.net\/wordpress\/wp-json\/wp\/v2\/media\/496187"}],"wp:attachment":[{"href":"https:\/\/www.radiopiu.net\/wordpress\/wp-json\/wp\/v2\/media?parent=496188"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.radiopiu.net\/wordpress\/wp-json\/wp\/v2\/categories?post=496188"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.radiopiu.net\/wordpress\/wp-json\/wp\/v2\/tags?post=496188"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}