{"id":496190,"date":"2026-02-11T17:19:46","date_gmt":"2026-02-11T16:19:46","guid":{"rendered":"https:\/\/www.radiopiu.net\/wordpress\/?p=496190"},"modified":"2026-02-11T17:19:46","modified_gmt":"2026-02-11T16:19:46","slug":"stati-generali-delle-associazioni-36-realta-unite-per-il-patto-di-sedico-2026","status":"publish","type":"post","link":"https:\/\/www.radiopiu.net\/wordpress\/stati-generali-delle-associazioni-36-realta-unite-per-il-patto-di-sedico-2026\/","title":{"rendered":"STATI GENERALI DELLE ASSOCIAZIONI: 36 REALT\u00c0 UNITE PER IL \u201cPATTO DI SEDICO\u201d 2026"},"content":{"rendered":"<p>*******<\/p>\n<p>&nbsp;<\/p>\n<p><strong><a class=\"dt-pswp-item\" href=\"https:\/\/www.radiopiu.net\/wordpress\/wp-content\/uploads\/2026\/02\/5017e2a3-cead-4b77-a89b-b96b9d4e0c05.jpg\" data-dt-img-description=\"\" data-large_image_width=\"2048\" data-large_image_height=\"1536\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter  wp-image-496191\" src=\"https:\/\/www.radiopiu.net\/wordpress\/wp-content\/uploads\/2026\/02\/5017e2a3-cead-4b77-a89b-b96b9d4e0c05-300x225.jpg\" alt=\"\" width=\"184\" height=\"138\" srcset=\"https:\/\/www.radiopiu.net\/wordpress\/wp-content\/uploads\/2026\/02\/5017e2a3-cead-4b77-a89b-b96b9d4e0c05-300x225.jpg 300w, https:\/\/www.radiopiu.net\/wordpress\/wp-content\/uploads\/2026\/02\/5017e2a3-cead-4b77-a89b-b96b9d4e0c05-1024x768.jpg 1024w, https:\/\/www.radiopiu.net\/wordpress\/wp-content\/uploads\/2026\/02\/5017e2a3-cead-4b77-a89b-b96b9d4e0c05-768x576.jpg 768w, https:\/\/www.radiopiu.net\/wordpress\/wp-content\/uploads\/2026\/02\/5017e2a3-cead-4b77-a89b-b96b9d4e0c05-1536x1152.jpg 1536w, https:\/\/www.radiopiu.net\/wordpress\/wp-content\/uploads\/2026\/02\/5017e2a3-cead-4b77-a89b-b96b9d4e0c05.jpg 2048w\" sizes=\"auto, (max-width: 184px) 100vw, 184px\" \/><\/a>\u00a0<\/strong><\/p>\n<p><strong>SEDICO\u00a0 <\/strong>Una partecipazione straordinaria ha segnato gli\u00a0Stati Generali delle Associazioni di Sedico, ospitati presso il\u00a0Centro Parrocchiale delle Roe. Ben\u00a036 s associazioni hanno risposto all&#8217;appello dell\u2019Amministrazione Comunale, trasformando l&#8217;incontro in un vero laboratorio di progettazione per il 2026. L&#8217;incontro ha messo al centro la forza del volontariato locale.\u00a0\u201cVedere 36 associazioni sedute allo stesso tavolo \u00e8 la prova che Sedico \u00e8 una comunit\u00e0 viva e pronta a collaborare,\u201d ha dichiarato l\u2019Amministrazione.\u00a0 Le associazioni sono il battito cardiaco di Sedico,\u201d\u00a0\u00e8 stato dichiarato in apertura.\u00a0\u201cDalle frazioni al centro, il loro impegno garantisce identit\u00e0 e coesione. Il nostro compito \u00e8 fornire loro gli strumenti per operare al meglio.\u201d Durante la serata, oltre alla presentazione delle iniziative intraprese dall\u2019amministrazione per supportare i volontari, \u00e8 stato proposto il\u00a0Calendario Unico degli Eventi, uno strumento strategico per coordinare le manifestazioni nel centro e nelle frazioni, cercando di evitare sovrapposizioni e valorizzando ogni singola realt\u00e0. Sul i tavoli tecnici sono stati affrontati temi centrali come la semplificazione delle pratiche di sicurezza, la comunicazione integrata attraverso i canali comunali e il format &#8220;Mezz&#8217;ora con il Sindaco&#8221; che \u00e8 stato messo a disposizione delle Associazioni per la promozione delle proprie attivit\u00e0 direttamente ai\u00a0 cittadini interessati. I lavori si sono conclusi con un\u00a0momento conviviale che ha permesso ai rappresentanti delle 36 associazioni di confrontarsi in modo informale. Questo spazio di socialit\u00e0 \u00e8 stato fondamentale per approfondire conoscenze reciproche e far nascere nuove idee di collaborazione che superano i confini dei singoli statuti. Il &#8220;Patto di Sedico&#8221;, siglato idealmente alle Roe, segna l&#8217;inizio di una nuova stagione di eventi coordinati e di un supporto amministrativo sempre pi\u00f9 vicino a chi dedica il proprio tempo al bene comune.<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>********<\/p>\n","protected":false},"excerpt":{"rendered":"<p>******* &nbsp; \u00a0 SEDICO\u00a0 Una partecipazione straordinaria ha segnato gli\u00a0Stati Generali delle Associazioni di Sedico, ospitati presso il\u00a0Centro Parrocchiale delle Roe. Ben\u00a036 s associazioni hanno risposto all&#8217;appello dell\u2019Amministrazione Comunale, trasformando l&#8217;incontro in un vero laboratorio di progettazione per il 2026. L&#8217;incontro ha messo al centro la forza del volontariato locale.\u00a0\u201cVedere 36 associazioni sedute allo stesso&hellip;<\/p>\n","protected":false},"author":4,"featured_media":496191,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":""},"categories":[51,49],"tags":[],"class_list":["post-496190","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-evidenza-top","category-news-18","category-51","category-49","description-off"],"img_url":"https:\/\/www.radiopiu.net\/wordpress\/wp-content\/uploads\/2026\/02\/5017e2a3-cead-4b77-a89b-b96b9d4e0c05.jpg","_links":{"self":[{"href":"https:\/\/www.radiopiu.net\/wordpress\/wp-json\/wp\/v2\/posts\/496190","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.radiopiu.net\/wordpress\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.radiopiu.net\/wordpress\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.radiopiu.net\/wordpress\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.radiopiu.net\/wordpress\/wp-json\/wp\/v2\/comments?post=496190"}],"version-history":[{"count":0,"href":"https:\/\/www.radiopiu.net\/wordpress\/wp-json\/wp\/v2\/posts\/496190\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.radiopiu.net\/wordpress\/wp-json\/wp\/v2\/media\/496191"}],"wp:attachment":[{"href":"https:\/\/www.radiopiu.net\/wordpress\/wp-json\/wp\/v2\/media?parent=496190"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.radiopiu.net\/wordpress\/wp-json\/wp\/v2\/categories?post=496190"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.radiopiu.net\/wordpress\/wp-json\/wp\/v2\/tags?post=496190"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}