{"id":64280,"date":"2018-10-17T17:29:15","date_gmt":"2018-10-17T15:29:15","guid":{"rendered":"http:\/\/www.radiopiu.net\/wordpress\/?p=64280"},"modified":"2018-10-17T17:37:17","modified_gmt":"2018-10-17T15:37:17","slug":"prezzi-dei-carburanti-alle-stelle-roccon-al-via-subito-una-raccolta-firme","status":"publish","type":"post","link":"https:\/\/www.radiopiu.net\/wordpress\/prezzi-dei-carburanti-alle-stelle-roccon-al-via-subito-una-raccolta-firme\/","title":{"rendered":"PREZZI DEI CARBURANTI ALLE STELLE &#8211; ROCCON \u201cAL VIA SUBITO UNA RACCOLTA FIRME\u201d"},"content":{"rendered":"<p><a class=\"dt-pswp-item\" href=\"http:\/\/www.radiopiu.net\/wordpress\/wp-content\/uploads\/2018\/10\/gasolio.jpeg\" data-dt-img-description=\"\" data-large_image_width=\"1282\" data-large_image_height=\"1082\"><img loading=\"lazy\" decoding=\"async\" class=\"alignleft wp-image-64282 size-medium\" src=\"http:\/\/www.radiopiu.net\/wordpress\/wp-content\/uploads\/2018\/10\/gasolio-300x253.jpeg\" alt=\"\" width=\"300\" height=\"253\" srcset=\"https:\/\/www.radiopiu.net\/wordpress\/wp-content\/uploads\/2018\/10\/gasolio-300x253.jpeg 300w, https:\/\/www.radiopiu.net\/wordpress\/wp-content\/uploads\/2018\/10\/gasolio-768x648.jpeg 768w, https:\/\/www.radiopiu.net\/wordpress\/wp-content\/uploads\/2018\/10\/gasolio-1024x864.jpeg 1024w, https:\/\/www.radiopiu.net\/wordpress\/wp-content\/uploads\/2018\/10\/gasolio.jpeg 1282w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a><\/p>\n<p>Dagli agenti di commercio uniti in Usarci parte un grido di protesta: \u201csui costi di gasolio e benzina subito un intervento del Governo\u201d. Il motivo \u00e8 presto detto. L\u2019oscillamento dei prezzi ha visto una definitiva impennata nell\u2019ottobre 2018, quando il valore al litro ha raggiunto 1,664 per benzina e 1,560 per gasolio. Una crescita ingiustificata, secondo l\u2019Unione sindacale agenti e rappresentanti di commercio di Belluno e del Veneto, dal momento che da anni il costo al barile oscilla tra72 e 75 dollari.<br \/>\nDi contro in Italia gli aumenti, nel corso dell\u2019ultimo anno, si attestano attorno a quasi il 10% per la benzina e al 13,5% per il gasolio, una crescita che si ripercuote di conseguenza sui costi e sul fatturato della categoria che, ora, ha deciso di dire \u201cBasta!\u201d e di passare all\u2019azione.<br \/>\n\u201cChiediamo a gran voce un intervento governativo \u2013 afferma Franco Roccon il presidente di USARCI Veneto, il sindacato che affianca e tutela gli agenti di commercio -, perch\u00e9 gli aumenti abbiano una concreta giustificazione e non siano mera speculazione di petrolieri senza scrupoli. Richiamiamo il Governo al suo dovere, ad intervenire e applicare quanto annunciato pi\u00f9 volte; parlo dell\u2019eliminazione di accise sui carburanti che incidono notevolmente sul costo al litro e che riguardano ancora eventi come il Vajont, i vari terremoti degli ultimi 50 anni, perfino guerre del secolo scorso, operazioni che ormai hanno abbondantemente coperto i costi statali degli interventi. Non si pu\u00f2 fare cassa sempre e solo su chi utilizza l\u2019auto; per gli agenti e i rappresentanti di commercio la vettura \u00e8 il principale ed insostituibile mezzo di lavoro\u201d.<br \/>\nIl piano \u00e8 chiaro, le azioni decise.<br \/>\n\u201cAvvieremo, nell\u2019interesse dei quasi 30 mila agenti operanti nel Veneto, una raccolta firme on line attraverso Change.org \u2013 spiega il presidente &#8211; per sensibilizzare il Governo e i suoi rappresentanti e spingerli ad intervenire immediatamente per monitorare gli aumenti ingiustificati che dal febbraio 2016 hanno visto impennarsi il costo dei carburanti, passati silenziosamente in soli due anni, da 1,370 a 1,522\u20ac\/litro la benzina, con un +21% e con il gasolio da 1,181 a 1,560 euro al litro con un +32%. Il costo della vita certamente non ha seguito lo stesso andamento e nemmeno gli aumenti delle provvigioni che gli agenti incassano con il proprio lavoro. Urge intervenire immediatamente\u201d.<\/p>\n<p>CLICCARE SULLE IMMAGINI PER INGRANDIRE<\/p>\n<p><a class=\"dt-pswp-item\" href=\"http:\/\/www.radiopiu.net\/wordpress\/wp-content\/uploads\/2018\/10\/benzina.jpeg\" data-dt-img-description=\"\" data-large_image_width=\"976\" data-large_image_height=\"508\"><img loading=\"lazy\" decoding=\"async\" class=\"size-medium wp-image-64283 alignleft\" src=\"http:\/\/www.radiopiu.net\/wordpress\/wp-content\/uploads\/2018\/10\/benzina-300x156.jpeg\" alt=\"\" width=\"300\" height=\"156\" srcset=\"https:\/\/www.radiopiu.net\/wordpress\/wp-content\/uploads\/2018\/10\/benzina-300x156.jpeg 300w, https:\/\/www.radiopiu.net\/wordpress\/wp-content\/uploads\/2018\/10\/benzina-768x400.jpeg 768w, https:\/\/www.radiopiu.net\/wordpress\/wp-content\/uploads\/2018\/10\/benzina.jpeg 976w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a><br \/>\nSegretario Regionale<\/p>\n<p>USARCIVENETO<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Dagli agenti di commercio uniti in Usarci parte un grido di protesta: \u201csui costi di gasolio e benzina subito un intervento del Governo\u201d. Il motivo \u00e8 presto detto. L\u2019oscillamento dei prezzi ha visto una definitiva impennata nell\u2019ottobre 2018, quando il valore al litro ha raggiunto 1,664 per benzina e 1,560 per gasolio. Una crescita ingiustificata,&hellip;<\/p>\n","protected":false},"author":1,"featured_media":64281,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":""},"categories":[49],"tags":[],"class_list":["post-64280","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-news-18","category-49","description-off"],"img_url":"https:\/\/www.radiopiu.net\/wordpress\/wp-content\/uploads\/2018\/10\/crisi-gasolio.jpg","_links":{"self":[{"href":"https:\/\/www.radiopiu.net\/wordpress\/wp-json\/wp\/v2\/posts\/64280","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.radiopiu.net\/wordpress\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.radiopiu.net\/wordpress\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.radiopiu.net\/wordpress\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.radiopiu.net\/wordpress\/wp-json\/wp\/v2\/comments?post=64280"}],"version-history":[{"count":0,"href":"https:\/\/www.radiopiu.net\/wordpress\/wp-json\/wp\/v2\/posts\/64280\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.radiopiu.net\/wordpress\/wp-json\/wp\/v2\/media\/64281"}],"wp:attachment":[{"href":"https:\/\/www.radiopiu.net\/wordpress\/wp-json\/wp\/v2\/media?parent=64280"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.radiopiu.net\/wordpress\/wp-json\/wp\/v2\/categories?post=64280"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.radiopiu.net\/wordpress\/wp-json\/wp\/v2\/tags?post=64280"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}